{"id":958,"date":"2026-05-09T18:49:00","date_gmt":"2026-05-09T18:49:00","guid":{"rendered":"https:\/\/www.mareg-motive.com\/coaching\/?p=958"},"modified":"2026-05-09T18:49:00","modified_gmt":"2026-05-09T18:49:00","slug":"burtenbach","status":"publish","type":"post","link":"https:\/\/www.mareg-motive.com\/coaching\/burtenbach\/","title":{"rendered":"Coaching Burtenbach &#8211; &#8599;&#65039;mareg GbR: &#10004;&#65039;Teambilding, Mitarbeiterbindung, Pers&ouml;nlichkeitsentwicklung, F&uuml;hrungskr&auml;ftecoaching"},"content":{"rendered":"<h1><img decoding=\"async\" src=\"https:\/\/www.mareg-motive.com\/coaching\/wp-content\/uploads\/2024\/10\/Coaching.png\" alt=\"Coaching Burtenbach - &#8599;&#65039;mareg GbR: &#10004;&#65039;Pers&ouml;nlichkeitsentwicklung, Mitarbeiterbindung, Teambilding, F&uuml;hrungskr&auml;ftecoaching\" \/><\/h1>\n<h2><img decoding=\"async\" src=\"https:\/\/www.mareg-motive.com\/coaching\/wp-content\/uploads\/2024\/10\/Mitarbeitergewinnung.png\" alt=\"Mitarbeitergewinnung &#038; Mitarbeiterbindung: Ihr &#9989; Coach &#038; Motivationstrainer \" \/><\/h2>\n<p><strong>Coaching Burtenbach &#8211; &#8599;&#65039;mareg GbR: &#10004;&#65039;Mitarbeiterbindung, Pers&ouml;nlichkeitsentwicklung, Teambilding, F&uuml;hrungskr&auml;ftecoaching. Sie haben nach &#10004;&#65039; Teambilding, &#10004;&#65039; Mitarbeiterbindung, &#10004;&#65039; Coaching, &#10004;&#65039; Pers&ouml;nlichkeitsentwicklung und &#10004;&#65039; F&uuml;hrungskr&auml;ftecoaching gesucht? &#10145;&#65039; mareg GbR, Ihr Coach &#038; Motivationstrainer in 89349 Burtenbach. Treten Sie in Kontakt mit uns &#9993;.<\/strong><\/p>\n<p><!--more--><\/p>\n\n<p><b><a href=\"\/coaching\/kontakt\/\">&#9742;&#65039; Nutzen Sie unser Kontaktformular. <\/a><\/b><\/p>\n<p><\/br><\/p>\n<div class=\"Informationen\">\n<div>\n\t\t<img decoding=\"async\" src=\"https:\/\/www.mareg-motive.com\/coaching\/wp-content\/uploads\/2024\/10\/Teambilding.png\" alt=\"Teambilding f&uuml;r  Burtenbach, Ziemetshausen, R&ouml;fingen, Ellzee, Kammeltal, Neuburg (Kammel), Ursberg und M&uuml;nsterhausen, Jettingen-Scheppach, Thannhausen\" \/><\/p>\n<h3>ERKENNE IHRE MOTIVATIONSKRAFT<\/h3>\n<p>Mit dem Erkennen Deiner Motivationsfaktoren kannst Du Dein Handeln in verschiedenen Momenten klarer deuten und daraufhin anpassen.<\/p>\n<p>\t\t<a href=\"\/motivationspotenzialanalyse\/\"><img decoding=\"async\" src=\"https:\/\/www.mareg-motive.com\/coaching\/wp-content\/uploads\/2024\/10\/Motivation.png\" alt=\"Motivation \" \/><\/a>\n\t\t<\/div>\n<div>\n\t\t <img decoding=\"async\" src=\"https:\/\/www.mareg-motive.com\/coaching\/wp-content\/uploads\/2024\/10\/Persoenlichkeitsentwicklung.png\" alt=\"Pers&ouml;nlichkeitsentwicklung f&uuml;r  Burtenbach - Kemnat, Oberwaldbach und Humprechtsm&uuml;hle\" \/><\/p>\n<h3>MIT MOTIVEN ANZEIGEN ENTWERFEN<\/h3>\n<p>Unsere Marketingkampagnen erzeugen Gef&uuml;hle und k&uuml;sst versteckte W&uuml;nsche wach bei Deiner Zielgruppe.<\/p>\n<p><a href=\"\/marketing\/\"><img decoding=\"async\" src=\"https:\/\/www.mareg-motive.com\/coaching\/wp-content\/uploads\/2024\/10\/Werbung.png\" alt=\"Werbung \" \/><\/a>\n<\/div>\n<\/p><\/div>\n<h2>Herzlich willkommen in unserer Motivwelt.<\/h2>\n<h3>Wir sind R f&uuml;r Burtenbach. und M f&uuml;r Burtenbach. &ndash; zwei kreative K&ouml;pfe und Begleiter f&uuml;r Burtenbach. <\/h3>\n<p>F&uuml;r  Burtenbach, Ziemetshausen, R&ouml;fingen, Ellzee, Kammeltal, Neuburg (Kammel), Ursberg oder M&uuml;nsterhausen, Jettingen-Scheppach, Thannhausen: Inspirationen und Konzepte begegnen uns in kreativen Ausdrucksformen, T&ouml;nen und in dem pers&ouml;nlichen Ausdruck.Unabh&auml;ngig davon ob privat oder beruflich, Motive wirken.Es sind diese Motive, die uns begleiten und mit denen wir uns auseinandersetzen.<\/p>\n<div class=\"Informationen\">\n<div>\n\t\t<img decoding=\"async\" src=\"https:\/\/www.mareg-motive.com\/coaching\/wp-content\/uploads\/2024\/10\/Resilienz.png\" alt=\"Resilienz in  Burtenbach\" \/><\/br><br \/>\n\t\t<a href=\"mailto:marvin@mareg-motive.com\"><img decoding=\"async\" src=\"https:\/\/www.mareg-motive.com\/coaching\/wp-content\/uploads\/2024\/10\/Mitarbeitermotivation.png\" alt=\"F&uuml;hrungskr&auml;ftecoaching &#038; Mitarbeitermotivation in  Burtenbach\" \/><\/a>\n\t\t<\/div>\n<div>\n\t\t<img decoding=\"async\" src=\"https:\/\/www.mareg-motive.com\/coaching\/wp-content\/uploads\/2024\/10\/Burnout.png\" alt=\"Burnout \" \/><\/br><br \/>\n\t\t<a href=\"mailto:regina@mareg-motive.com\"><img decoding=\"async\" src=\"https:\/\/www.mareg-motive.com\/coaching\/wp-content\/uploads\/2024\/10\/Supervision.png\" alt=\"Empowerment &#038; Supervision in 89349 Burtenbach\" \/><\/a>\n<\/div>\n<\/p><\/div>\n<p><img decoding=\"async\" src=\"https:\/\/www.mareg-motive.com\/coaching\/wp-content\/uploads\/2024\/10\/Empowerment.png\" alt=\"Empowerment f&uuml;r  Burtenbach\" \/><a href=\"\/coaching\/kontakt\/\"><img decoding=\"async\" src=\"https:\/\/www.mareg-motive.com\/coaching\/wp-content\/uploads\/2024\/10\/Leadership-training.png\" alt=\"Leadership training f&uuml;r  Burtenbach\" \/><\/a><\/p>\n<div class=\"info-container\">\n<div class=\"info-buttons\">\n<button class=\"infolink active\" onclick=\"openInfo(event, 'Info1')\">mareg GbR<\/button><br \/>\n<button class=\"infolink\" onclick=\"openInfo(event, 'Info2')\">Ihr Coach &#038; Motivationstrainer<\/button><br \/>\n<button class=\"infolink\" onclick=\"openInfo(event, 'Info3')\">in Burtenbach<\/button>\n<\/div>\n<div id=\"Info1\" class=\"info-content active\">\n<\/p>\n<h4>Informationen &uuml;ber Burtenbach<\/h4>\n<div style=\"float:left; width: 80%;\">Burtenbach&#8230; <\/p>\n<p><b>Burtenbach<\/b> ist ein Markt im schw&auml;bischen Landkreis G&uuml;nzburg.<\/p>\n<\/div>\n<div style=\"float:right; width: 20%; text-align:center\"><img alt='Wappen des Marktes Burtenbach' title='Wappen des Marktes Burtenbach' src='\/\/upload.wikimedia.org\/wikipedia\/commons\/thumb\/5\/58\/Wappen_von_Burtenbach.svg\/140px-Wappen_von_Burtenbach.svg.png' width='140' height='149' srcset='\/\/upload.wikimedia.org\/wikipedia\/commons\/thumb\/5\/58\/Wappen_von_Burtenbach.svg\/210px-Wappen_von_Burtenbach.svg.png 1.5x, \/\/upload.wikimedia.org\/wikipedia\/commons\/thumb\/5\/58\/Wappen_von_Burtenbach.svg\/280px-Wappen_von_Burtenbach.svg.png 2x'><\/div>\n<div style=\"margin-top:150px\"><\/div>\n<p>\n\n<\/div>\n<div id=\"Info2\" class=\"info-content\">\n<\/p>\n<h2>Verlassen Sie sich auf mareg GbR, Ihren Coach &#038; Motivationstrainer in Coaching f&uuml;r Burtenbach, Bayern, wenn es um erstklassige Leistungen geht.<\/h2>\n<p>\n\n<ul>\n<li><a href=\"#Teambilding\">Teambilding<\/a><\/li>\n<li><a href=\"#F&uuml;hrungskr&auml;ftecoaching\">F&uuml;hrungskr&auml;ftecoaching<\/a><\/li>\n<li><a href=\"#Mitarbeiterbindung\">Mitarbeiterbindung<\/a><\/li>\n<li><a href=\"#Pers&ouml;nlichkeitsentwicklung\">Pers&ouml;nlichkeitsentwicklung<\/a><\/li>\n<\/ul>\n\n\n<\/p>\n<h2>Coaching aus  Burtenbach, M&uuml;nsterhausen, Jettingen-Scheppach, Thannhausen, Ziemetshausen, R&ouml;fingen, Ellzee oder Kammeltal, Neuburg (Kammel), Ursberg gesucht? mareg GbR ist der richtige Coach &#038; Motivationstrainer f&uuml;r Coaching.<\/h2>\n<p>\n<h2>Coaching in  Burtenbach,   gesucht? Mit mareg GbR haben Sie den besten Coach &#038; Motivationstrainer f&uuml;r Coaching &#038; Trainer in Ihrer N&auml;he gefunden.<\/h2>\n<ul>\n<li>Au&szlig;ergew&ouml;hnliche Mitarbeiterbindung, Work-Life-Balance gestalten, die f&uuml;r Qualit&auml;t stehen<\/li>\n<li>Teambilding Ma&szlig;nahmen, Work-Life-Balance gestalten aus  Burtenbach, mit Fokus auf Individualit&auml;t<\/li>\n<li>Pers&ouml;nlichkeitsentwicklungen, Kommunikation im Team verbessern <\/li>\n<li>\n<li>Individuelle Coaching, Motivationspotenziale f&uuml;r Bayern<\/li>\n<\/li>\n<li>F&uuml;hrungskr&auml;ftecoaching, Karriereberatung f&uuml;r  Burtenbach   <\/li>\n<\/ul>\n<p>F&uuml;r Coaching &#038; Trainer sind wir Ihr kompetenter Fachmann sowie bei Mitarbeiterbindung ebenso ein fachkundiger Coach &#038; Motivationstrainer. &Uuml;berzeugen Sie sich selber von unseren hochwertigen Mitarbeiterbindung &#038; motivieren, Teambilding Ma&szlig;nahmen, Coaching &#038; Trainer, Pers&ouml;nlichkeitsentwicklungen und Mitarbeiter motivieren und koordinieren Sie einen Beratungstermin!<\/p>\n<h3>Preiswerte Coaching &#038; Trainer f&uuml;r  Burtenbach    -Entscheiden Sie sich f&uuml;r uns<\/h3>\n<p>Bei Ihnen in  Burtenbach    suchen Sie funktionelle Coaching &#038; Trainer?Ihnen produzieren wir als erfahrene Firma das Coaching und Motivationspotenziale, Coach &#038; Motivator oder Mitarbeitermotivation &#038; Mitarbeiter finden Ihrer Wahl. Vielf&auml;ltige Coaching &#038; Trainer k&ouml;nnen Sie bei uns entdecken.Stehen die Coaching &#038; Trainer zur Auswahl: Pers&ouml;nlichkeitsentwicklung. Als professioneller Coach &#038; Motivationstrainer der gew&uuml;nschten Coaching &#038; Trainer k&ouml;nnen wir Ihnen verschiedenste Offerten machen.Gern produzieren wir f&uuml;r Sie das Coaching, Motivationspotenziale, Coach &#038; Motivator wie auch Mitarbeitermotivation &#038; Mitarbeiter finden nach Ihren Vorstellungen. <\/p>\n<\/p>\n<p><b>Ganz egal ob Sie nach Coaching, Mitarbeitermotivation &#038; Mitarbeiter finden, Motivationspotenziale, Coach &#038; Motivator, Mitarbeiterbindung &#038; motivieren und Teambilding Ma&szlig;nahmen, Work-Life-Balance gestalten, Empowerment &#038; Supervision, Work-Life-Balance gestalten, Mitarbeiter binden, Resilienz, Burnout &#038; Burnouthilfe, Pers&ouml;nlichkeitsentwicklung sowie Leadership training, Kommunikation im Team verbessern, Mitarbeitergewinnung &#038; Mitarbeiterf&ouml;rderung, Mitarbeiter motivieren oder Karriereberatung, Konflikte konstruktiv bew&auml;ltigen, Entscheidungsr&auml;ume schaffen gesucht haben -> mareg GbR, Ihr Coach &#038; Motivationstrainer f&uuml;r das ganze Gebiet Burtenbach<b><\/p>\n<p>\n<p><a name=\"Teambilding\"><\/a><\/p>\n<h2>Ihr Coach &#038; Motivationstrainer  bietet Ihnen das Teambilding Ihrer W&uuml;nsche! <\/h2>\n\n<\/p>\n<p>Ben&ouml;tigen Sie Coaching ma&szlig;geschneidert auf Ihre eigenen Erwartungen?  Warum ist auf uns Verlass? Wir haben f&uuml;r jeden Anspruch die angemessenen Coaching &#038; Trainer. Die L&ouml;sung, die jeden zufrieden stellt, gibt es nicht. Also geh&ouml;rt es zu unserer hohen Fachkompetenz und nachweisbaren Erfahrung, <strong>Teambilding, Empowerment &#038; Supervision, Resilienz oder Work-Life-Balance gestalten<\/strong> in unterschiedlichen Versionen anzubieten. <\/p>\n<p>\n<h3>Preiswerte Teambilding, Empowerment &#038; Supervision, Resilienz, Work-Life-Balance gestalten in  gesucht? Ebenfalls f&uuml;r Empowerment &#038; Supervision, Resilienz und Work-Life-Balance gestalten sind wir Ihr Fachmann<\/h3>\n\n\n\n<\/p>\n<p>Als mehrj&auml;hrig t&auml;tige Firma fertigen wir f&uuml;r Sie Ihr <strong>Teambilding, Empowerment &#038; Supervision, Resilienz und Work-Life-Balance gestalten<\/strong> so, dass Ihnen die gr&ouml;&szlig;tm&ouml;gliche Anpassungsf&auml;higkeit geboten wird.  In den unterschiedlichsten Variationen erh&auml;ltlich sind unsre Teambilding Ma&szlig;nahmen, so dass Sie sich bei unserem Betrieb <b>Teambilding<\/b> Ihrer Wahl aussuchen.  Unsre Teambilding Ma&szlig;nahmen nach Ihren Anspr&uuml;chen nutzen? Wir richten uns nach Ihren Wollen.<\/p>\n<p>\n<p><a name=\"Pers&ouml;nlichkeitsentwicklung\"><\/a><\/p>\n<h2>Pers&ouml;nlichkeitsentwicklung: Pers&ouml;nlichkeitsentwicklungen von mareg GbR begeistern durch Beschaffenheit.  <\/h2>\n<\/p>\n<ol>\n<li>Individuelle Pers&ouml;nlichkeitsentwicklung, Kommunikation im Team verbessern, Leadership training, Mitarbeitergewinnung &#038; Mitarbeiterf&ouml;rderung<\/li>\n<li>Leadership training , Ziemetshausen, R&ouml;fingen, Ellzee, Kammeltal, Neuburg (Kammel), Ursberg und M&uuml;nsterhausen, Jettingen-Scheppach, Thannhausen<\/li>\n<li>Einmalige Pers&ouml;nlichkeitsentwicklungen<\/li>\n<li>Kommunikation im Team verbessern GZ, KRU<\/li>\n<li>Mitarbeitergewinnung &#038; Mitarbeiterf&ouml;rderung  &#8211; Kemnat, Oberwaldbach oder Humprechtsm&uuml;hle<\/li>\n<\/ol>\n<p> \n<\/p>\n<p> Als Marktf&uuml;hrer im Bereich Pers&ouml;nlichkeitsentwicklung, Leadership training, Mitarbeitergewinnung &#038; Mitarbeiterf&ouml;rderung, Kommunikation im Team verbessern sind Sie bei mareg GbR genau richtig. Im Bereich Pers&ouml;nlichkeitsentwicklungen offeriert Ihnen unser hervorragend geschultes Personal perfekten Service. Eine z&uuml;gige und zuverl&auml;ssige Ausf&uuml;hrung ist naturgem&auml;&szlig;. <\/p>\n<p> \n<h2>Pers&ouml;nlichkeitsentwicklung und Coaching  gesucht? mareg GbR ist Ihr Experte f&uuml;r Pers&ouml;nlichkeitsentwicklungen, Coaching &#038; Trainer oder Teambilding<\/h2>\n\n\n\n\n<p><a name=\"Mitarbeiterbindung\"><\/a><\/p>\n<h2>Mitarbeiterbindung, Mitarbeiter binden, Work-Life-Balance gestalten ebenso wie Burnout &#038; Burnouthilfe werden Ihnen von uns geboten<\/h2>\n\n<\/p>\n<p> Von uns erhalten Sie hier alles aus einer Hand. Noch dazu geh&ouml;rt dies und jenes, was man unter Mitarbeiterbindung, Mitarbeiter binden, Work-Life-Balance gestalten oder Burnout &#038; Burnouthilfe versteht. Unser Sortiment l&auml;sst sich hier ma&szlig;geschneidert anpassen. Genauso im Nachhinein k&ouml;nnen Sie diese Kraft nutzen. <\/p>\n<p>\n<h2>G&uuml;nstige Mitarbeiterbindung in  Burtenbach gesucht? Ebenso f&uuml;r Mitarbeiter binden, Work-Life-Balance gestalten und Burnout &#038; Burnouthilfe sind wir Ihr Experte<\/h2>\n\n\n\n\n<p><a name=\"F&uuml;hrungskr&auml;ftecoaching\"><\/a><\/p>\n<h2>Hochwertige Mitarbeiter motivieren ebenfalls !<\/h2>\n\n<\/p>\n<p>F&uuml;hrungskr&auml;ftecoaching, Karriereberatung, Konflikte konstruktiv bew&auml;ltigen oder Entscheidungsr&auml;ume schaffen ist einmalig f&uuml;r Unternehmen in der Kategorie und eines der besten Verkaufsprodukte seit Jahren.  Entt&auml;uscht? Das werden Sie nicht werden. Eine Verkaufsgarantie erhalten Sie mit der Mitarbeiter motivieren Reihe.  Mit diesem Produkt <dfn>F&uuml;hrungskr&auml;ftecoaching<\/dfn> haben Sie die allerbeste Argumente auf ihrer Seite, falls Sie mit Erfolg werden wollen. Sie m&ouml;chten zielf&uuml;hrend werden? <\/p>\n<p>\n<h2>F&uuml;hrungskr&auml;ftecoaching und Coaching  gesucht? mareg GbR ist Ihr Profi f&uuml;r Mitarbeiter motivieren, Coaching &#038; Trainer oder F&uuml;hrungskr&auml;ftecoaching<\/h2>\n<\/p>\n<ol>\n<li>Entscheidungsr&auml;ume schaffen GZ, KRU<\/li>\n<li>Einmalige Konflikte konstruktiv bew&auml;ltigen<\/li>\n<li>Karriereberatung<\/li>\n<li>F&uuml;hrungskr&auml;ftecoaching, Konflikte konstruktiv bew&auml;ltigen, Karriereberatung, Entscheidungsr&auml;ume schaffen<\/li>\n<\/ol>\n<p> \n\n\n\n<\/div>\n<div id=\"Info3\" class=\"info-content\">\n<p><b>Sie haben einen Burtenbacher Coach &#038; Motivationstrainer aus dem Bereich 08285 gesucht?<\/b><\/p>\n<p>Wollen Sie mehr erfahren? &#8211; Kontaktieren Sie uns  direkt in Burtenbach &#8211; <strong>Tel: 08285 659-716<\/strong><\/p>\n<h3>Unsere Leistungen in  Burtenbach (Bayern)<\/h3>\n<ul>\n<li>Teambilding in Bayern<\/li>\n\n<li>Coaching &#038; Trainer in 89349 Burtenbach Humprechtsm&uuml;hle, Kemnat, Oberwaldbach<\/li>\n<li>Mitarbeiterbindung aus  Burtenbach &#8211; Kemnat, Humprechtsm&uuml;hle oder Oberwaldbach<\/li>\n<li>Coaching in  Burtenbach, Kammeltal, Neuburg (Kammel), Ursberg, M&uuml;nsterhausen, Jettingen-Scheppach, Thannhausen oder Ziemetshausen, R&ouml;fingen, Ellzee<\/li>\n\n<\/ul>\n\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Coaching Burtenbach &#8211; &#8599;&#65039;mareg GbR: &#10004;&#65039;Mitarbeiterbindung, Pers&ouml;nlichkeitsentwicklung, Teambilding, F&uuml;hrungskr&auml;ftecoaching. Sie haben nach &#10004;&#65039; Teambilding, &#10004;&#65039; Mitarbeiterbindung, &#10004;&#65039; Coaching, &#10004;&#65039; Pers&ouml;nlichkeitsentwicklung und &#10004;&#65039; F&uuml;hrungskr&auml;ftecoaching gesucht? &#10145;&#65039; mareg GbR, Ihr Coach &#038; Motivationstrainer in 89349 Burtenbach. Treten Sie in Kontakt mit uns &#9993;.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","neve_meta_reading_time":"","footnotes":""},"categories":[4],"tags":[],"class_list":["post-958","post","type-post","status-publish","format-standard","hentry","category-coaching"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.mareg-motive.com\/coaching\/wp-json\/wp\/v2\/posts\/958","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mareg-motive.com\/coaching\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mareg-motive.com\/coaching\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mareg-motive.com\/coaching\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mareg-motive.com\/coaching\/wp-json\/wp\/v2\/comments?post=958"}],"version-history":[{"count":1,"href":"https:\/\/www.mareg-motive.com\/coaching\/wp-json\/wp\/v2\/posts\/958\/revisions"}],"predecessor-version":[{"id":1544,"href":"https:\/\/www.mareg-motive.com\/coaching\/wp-json\/wp\/v2\/posts\/958\/revisions\/1544"}],"wp:attachment":[{"href":"https:\/\/www.mareg-motive.com\/coaching\/wp-json\/wp\/v2\/media?parent=958"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mareg-motive.com\/coaching\/wp-json\/wp\/v2\/categories?post=958"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mareg-motive.com\/coaching\/wp-json\/wp\/v2\/tags?post=958"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}